{"id":211,"date":"2022-07-14T06:19:31","date_gmt":"2022-07-14T06:19:31","guid":{"rendered":"https:\/\/kadence.pixel-show.com\/local-butcher\/?p=211"},"modified":"2024-06-08T07:12:52","modified_gmt":"2024-06-08T07:12:52","slug":"spicy-meatballs-with-chermoula-sauce","status":"publish","type":"post","link":"https:\/\/almoosawirealestate.ae\/meat\/spicy-meatballs-with-chermoula-sauce\/","title":{"rendered":"Spicy meatballs with chermoula sauce"},"content":{"rendered":"<p class=\"wp-block-paragraph\">Dive into a burst of flavor with our spicy meatballs accompanied by vibrant chermoula sauce. These succulent meatballs are crafted with a tantalizing blend of ground meat, breadcrumbs, garlic, chili flakes, and a medley of aromatic spices, creating a symphony of taste and heat in every bite.<\/p><p class=\"wp-block-paragraph\">After a quick sear in a hot pan, the meatballs are bathed in a zesty chermoula sauce, bursting with the freshness of cilantro, parsley, lemon juice, garlic, and cumin. The tangy and herbaceous notes of the sauce perfectly complement the bold and fiery flavors of the meatballs, creating a harmonious fusion of tastes that will leave your palate tingling with delight.<\/p><p class=\"wp-block-paragraph\">Whether served as an appetizer at a gathering or as a main course with couscous or crusty bread, these spicy meatballs with chermoula sauce are guaranteed to tantalize your taste buds and leave you craving more of their irresistible allure. Embark on a culinary journey with this exotic and flavorful dish that promises to delight and satisfy with each and every bite.<\/p><style>.kb-row-layout-id211_12207d-58 > .kt-row-column-wrap{align-content:start;}:where(.kb-row-layout-id211_12207d-58 > .kt-row-column-wrap) > .wp-block-kadence-column{justify-content:start;}.kb-row-layout-id211_12207d-58 > .kt-row-column-wrap{column-gap:var(--global-kb-gap-md, 2rem);row-gap:var(--global-kb-gap-md, 2rem);padding-top:25px;padding-bottom:10px;}.kb-row-layout-id211_12207d-58 > .kt-row-column-wrap > div:not(.added-for-specificity){grid-column:initial;}.kb-row-layout-id211_12207d-58 > .kt-row-column-wrap{grid-template-columns:repeat(3, minmax(0, 1fr));}.kb-row-layout-id211_12207d-58 > .kt-row-layout-overlay{opacity:0.30;}@media all and (max-width: 1024px){.kb-row-layout-id211_12207d-58 > .kt-row-column-wrap > div:not(.added-for-specificity){grid-column:initial;}}@media all and (max-width: 1024px){.kb-row-layout-id211_12207d-58 > .kt-row-column-wrap{grid-template-columns:repeat(3, minmax(0, 1fr));}}@media all and (max-width: 767px){.kb-row-layout-id211_12207d-58 > .kt-row-column-wrap > div:not(.added-for-specificity){grid-column:initial;}.kb-row-layout-id211_12207d-58 > .kt-row-column-wrap{grid-template-columns:minmax(0, 1fr);}}<\/style><div class=\"kb-row-layout-wrap kb-row-layout-id211_12207d-58 alignnone wp-block-kadence-rowlayout\"><div class=\"kt-row-column-wrap kt-has-3-columns kt-row-layout-equal kt-tab-layout-inherit kt-mobile-layout-row kt-row-valign-top\">\n<style>.kadence-column211_7118fc-2f > .kt-inside-inner-col,.kadence-column211_7118fc-2f > .kt-inside-inner-col:before{border-top-left-radius:0px;border-top-right-radius:0px;border-bottom-right-radius:0px;border-bottom-left-radius:0px;}.kadence-column211_7118fc-2f > .kt-inside-inner-col{column-gap:var(--global-kb-gap-sm, 1rem);}.kadence-column211_7118fc-2f > .kt-inside-inner-col{flex-direction:column;}.kadence-column211_7118fc-2f > .kt-inside-inner-col > .aligncenter{width:100%;}.kadence-column211_7118fc-2f > .kt-inside-inner-col:before{opacity:0.3;}.kadence-column211_7118fc-2f{position:relative;}@media all and (max-width: 1024px){.kadence-column211_7118fc-2f > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}@media all and (max-width: 767px){.kadence-column211_7118fc-2f > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}<\/style>\n<div class=\"wp-block-kadence-column kadence-column211_7118fc-2f inner-column-1\"><div class=\"kt-inside-inner-col\"><style>.wp-block-kadence-column.kb-section-dir-horizontal > .kt-inside-inner-col > .kt-info-box211_40cdf4-1e .kt-blocks-info-box-link-wrap{max-width:unset;}.kt-info-box211_40cdf4-1e .kt-blocks-info-box-link-wrap{border-top:5px solid var(--global-palette8, #F7FAFC);border-right:5px solid var(--global-palette8, #F7FAFC);border-bottom:5px solid var(--global-palette8, #F7FAFC);border-left:5px solid var(--global-palette8, #F7FAFC);border-top-left-radius:0px;border-top-right-radius:0px;border-bottom-right-radius:0px;border-bottom-left-radius:0px;background:var(--global-palette8, #F7FAFC);padding-top:20px;padding-right:20px;padding-bottom:20px;padding-left:20px;}.kt-info-box211_40cdf4-1e .kt-blocks-info-box-link-wrap:hover{background:var(--global-palette7, #EDF2F7);}.kt-info-box211_40cdf4-1e .kadence-info-box-icon-container .kt-info-svg-icon, .kt-info-box211_40cdf4-1e .kt-info-svg-icon-flip, .kt-info-box211_40cdf4-1e .kt-blocks-info-box-number{font-size:30px;}.kt-info-box211_40cdf4-1e .kt-blocks-info-box-media{color:var(--global-palette9, #ffffff);background:var(--global-palette1, #3182CE);border-color:var(--global-palette8, #F7FAFC);border-top-width:0px;border-right-width:0px;border-bottom-width:0px;border-left-width:0px;padding-top:20px;padding-right:20px;padding-bottom:20px;padding-left:20px;}.kt-info-box211_40cdf4-1e .kt-blocks-info-box-media-container{margin-top:0px;margin-right:15px;margin-bottom:10px;margin-left:15px;}.kt-info-box211_40cdf4-1e .kt-blocks-info-box-link-wrap:hover .kt-blocks-info-box-media{color:var(--global-palette9, #ffffff);background:var(--global-palette2, #2B6CB0);}.kt-info-box211_40cdf4-1e .kt-infobox-textcontent h5.kt-blocks-info-box-title{padding-top:0px;padding-right:0px;padding-bottom:0px;padding-left:0px;margin-top:5px;margin-right:0px;margin-bottom:5px;margin-left:0px;}.kt-info-box211_40cdf4-1e .kt-infobox-textcontent .kt-blocks-info-box-text{color:#555555;}.kt-info-box211_40cdf4-1e .kt-blocks-info-box-learnmore{background:transparent;border-color:#555555;border-width:0px 0px 0px 0px;padding-top:4px;padding-right:8px;padding-bottom:4px;padding-left:8px;margin-top:10px;margin-right:0px;margin-bottom:10px;margin-left:0px;}.kt-info-box211_40cdf4-1e .kt-blocks-info-box-link-wrap:hover .kt-blocks-info-box-learnmore,.kt-info-box211_40cdf4-1e .kt-blocks-info-box-link-wrap .kt-blocks-info-box-learnmore:focus{color:#ffffff;background:#444444;border-color:#444444;}@media all and (max-width: 1024px){.kt-info-box211_40cdf4-1e .kt-blocks-info-box-link-wrap{border-top:5px solid var(--global-palette8, #F7FAFC);border-right:5px solid var(--global-palette8, #F7FAFC);border-bottom:5px solid var(--global-palette8, #F7FAFC);border-left:5px solid var(--global-palette8, #F7FAFC);}}@media all and (max-width: 767px){.kt-info-box211_40cdf4-1e .kt-blocks-info-box-link-wrap{border-top:5px solid var(--global-palette8, #F7FAFC);border-right:5px solid var(--global-palette8, #F7FAFC);border-bottom:5px solid var(--global-palette8, #F7FAFC);border-left:5px solid var(--global-palette8, #F7FAFC);}}<\/style>\n<div class=\"wp-block-kadence-infobox kt-info-box211_40cdf4-1e\"><span class=\"kt-blocks-info-box-link-wrap info-box-link kt-blocks-info-box-media-align-top kt-info-halign-center\"><div class=\"kt-blocks-info-box-media-container\"><div class=\"kt-blocks-info-box-media kt-info-media-animate-none\"><div class=\"kadence-info-box-icon-container kt-info-icon-animate-none\"><div class=\"kadence-info-box-icon-inner-container\"><span class=\"kb-svg-icon-wrap kb-svg-icon-fas_user-clock kt-info-svg-icon\"><svg viewBox=\"0 0 640 512\"  fill=\"currentColor\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"  aria-hidden=\"true\"><path d=\"M496 224c-79.6 0-144 64.4-144 144s64.4 144 144 144 144-64.4 144-144-64.4-144-144-144zm64 150.3c0 5.3-4.4 9.7-9.7 9.7h-60.6c-5.3 0-9.7-4.4-9.7-9.7v-76.6c0-5.3 4.4-9.7 9.7-9.7h12.6c5.3 0 9.7 4.4 9.7 9.7V352h38.3c5.3 0 9.7 4.4 9.7 9.7v12.6zM320 368c0-27.8 6.7-54.1 18.2-77.5-8-1.5-16.2-2.5-24.6-2.5h-16.7c-22.2 10.2-46.9 16-72.9 16s-50.6-5.8-72.9-16h-16.7C60.2 288 0 348.2 0 422.4V464c0 26.5 21.5 48 48 48h347.1c-45.3-31.9-75.1-84.5-75.1-144zm-96-112c70.7 0 128-57.3 128-128S294.7 0 224 0 96 57.3 96 128s57.3 128 128 128z\"\/><\/svg><\/span><\/div><\/div><\/div><\/div><div class=\"kt-infobox-textcontent\"><h5 class=\"kt-blocks-info-box-title\"><strong>Prep time<\/strong><\/h5><p class=\"kt-blocks-info-box-text\">25 mins<\/p><\/div><\/span><\/div><\/div><\/div>\n\n<style>.kadence-column211_e4bf4a-66 > .kt-inside-inner-col,.kadence-column211_e4bf4a-66 > .kt-inside-inner-col:before{border-top-left-radius:0px;border-top-right-radius:0px;border-bottom-right-radius:0px;border-bottom-left-radius:0px;}.kadence-column211_e4bf4a-66 > .kt-inside-inner-col{column-gap:var(--global-kb-gap-sm, 1rem);}.kadence-column211_e4bf4a-66 > .kt-inside-inner-col{flex-direction:column;}.kadence-column211_e4bf4a-66 > .kt-inside-inner-col > .aligncenter{width:100%;}.kadence-column211_e4bf4a-66 > .kt-inside-inner-col:before{opacity:0.3;}.kadence-column211_e4bf4a-66{position:relative;}@media all and (max-width: 1024px){.kadence-column211_e4bf4a-66 > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}@media all and (max-width: 767px){.kadence-column211_e4bf4a-66 > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}<\/style>\n<div class=\"wp-block-kadence-column kadence-column211_e4bf4a-66 inner-column-2\"><div class=\"kt-inside-inner-col\"><style>.wp-block-kadence-column.kb-section-dir-horizontal > .kt-inside-inner-col > .kt-info-box211_c2e465-18 .kt-blocks-info-box-link-wrap{max-width:unset;}.kt-info-box211_c2e465-18 .kt-blocks-info-box-link-wrap{border-top:5px solid var(--global-palette8, #F7FAFC);border-right:5px solid var(--global-palette8, #F7FAFC);border-bottom:5px solid var(--global-palette8, #F7FAFC);border-left:5px solid var(--global-palette8, #F7FAFC);border-top-left-radius:0px;border-top-right-radius:0px;border-bottom-right-radius:0px;border-bottom-left-radius:0px;background:var(--global-palette8, #F7FAFC);padding-top:20px;padding-right:20px;padding-bottom:20px;padding-left:20px;}.kt-info-box211_c2e465-18 .kt-blocks-info-box-link-wrap:hover{background:var(--global-palette7, #EDF2F7);}.kt-info-box211_c2e465-18 .kadence-info-box-icon-container .kt-info-svg-icon, .kt-info-box211_c2e465-18 .kt-info-svg-icon-flip, .kt-info-box211_c2e465-18 .kt-blocks-info-box-number{font-size:30px;}.kt-info-box211_c2e465-18 .kt-blocks-info-box-media{color:var(--global-palette9, #ffffff);background:var(--global-palette1, #3182CE);border-color:var(--global-palette8, #F7FAFC);border-top-width:0px;border-right-width:0px;border-bottom-width:0px;border-left-width:0px;padding-top:20px;padding-right:20px;padding-bottom:20px;padding-left:20px;}.kt-info-box211_c2e465-18 .kt-blocks-info-box-media-container{margin-top:0px;margin-right:15px;margin-bottom:10px;margin-left:15px;}.kt-info-box211_c2e465-18 .kt-blocks-info-box-link-wrap:hover .kt-blocks-info-box-media{color:var(--global-palette9, #ffffff);background:var(--global-palette2, #2B6CB0);}.kt-info-box211_c2e465-18 .kt-infobox-textcontent h5.kt-blocks-info-box-title{padding-top:0px;padding-right:0px;padding-bottom:0px;padding-left:0px;margin-top:5px;margin-right:0px;margin-bottom:5px;margin-left:0px;}.kt-info-box211_c2e465-18 .kt-infobox-textcontent .kt-blocks-info-box-text{color:#555555;}.kt-info-box211_c2e465-18 .kt-blocks-info-box-learnmore{background:transparent;border-color:#555555;border-width:0px 0px 0px 0px;padding-top:4px;padding-right:8px;padding-bottom:4px;padding-left:8px;margin-top:10px;margin-right:0px;margin-bottom:10px;margin-left:0px;}.kt-info-box211_c2e465-18 .kt-blocks-info-box-link-wrap:hover .kt-blocks-info-box-learnmore,.kt-info-box211_c2e465-18 .kt-blocks-info-box-link-wrap .kt-blocks-info-box-learnmore:focus{color:#ffffff;background:#444444;border-color:#444444;}@media all and (max-width: 1024px){.kt-info-box211_c2e465-18 .kt-blocks-info-box-link-wrap{border-top:5px solid var(--global-palette8, #F7FAFC);border-right:5px solid var(--global-palette8, #F7FAFC);border-bottom:5px solid var(--global-palette8, #F7FAFC);border-left:5px solid var(--global-palette8, #F7FAFC);}}@media all and (max-width: 767px){.kt-info-box211_c2e465-18 .kt-blocks-info-box-link-wrap{border-top:5px solid var(--global-palette8, #F7FAFC);border-right:5px solid var(--global-palette8, #F7FAFC);border-bottom:5px solid var(--global-palette8, #F7FAFC);border-left:5px solid var(--global-palette8, #F7FAFC);}}<\/style>\n<div class=\"wp-block-kadence-infobox kt-info-box211_c2e465-18\"><span class=\"kt-blocks-info-box-link-wrap info-box-link kt-blocks-info-box-media-align-top kt-info-halign-center\"><div class=\"kt-blocks-info-box-media-container\"><div class=\"kt-blocks-info-box-media kt-info-media-animate-none\"><div class=\"kadence-info-box-icon-container kt-info-icon-animate-none\"><div class=\"kadence-info-box-icon-inner-container\"><span class=\"kb-svg-icon-wrap kb-svg-icon-ic_timer kt-info-svg-icon\"><svg viewBox=\"0 0 8 8\"  fill=\"currentColor\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"  aria-hidden=\"true\"><path d=\"M2 0v1h1v.03c-1.7.24-3 1.71-3 3.47 0 1.93 1.57 3.5 3.5 3.5s3.5-1.57 3.5-3.5c0-.45-.1-.87-.25-1.25l-.91.38c.11.29.16.57.16.88 0 1.39-1.11 2.5-2.5 2.5s-2.5-1.11-2.5-2.5 1.11-2.5 2.5-2.5c.3 0 .59.05.88.16l.34-.94c-.23-.08-.47-.12-.72-.16v-.06h1v-1h-3zm5 1.16s-3.65 2.81-3.84 3c-.19.2-.19.49 0 .69.19.2.49.2.69 0 .2-.2 3.16-3.69 3.16-3.69z\"\/><\/svg><\/span><\/div><\/div><\/div><\/div><div class=\"kt-infobox-textcontent\"><h5 class=\"kt-blocks-info-box-title\"><strong>Cook time<\/strong><\/h5><p class=\"kt-blocks-info-box-text\">10 mins<\/p><\/div><\/span><\/div><\/div><\/div>\n\n<style>.kadence-column211_d518a6-d9 > .kt-inside-inner-col,.kadence-column211_d518a6-d9 > .kt-inside-inner-col:before{border-top-left-radius:0px;border-top-right-radius:0px;border-bottom-right-radius:0px;border-bottom-left-radius:0px;}.kadence-column211_d518a6-d9 > .kt-inside-inner-col{column-gap:var(--global-kb-gap-sm, 1rem);}.kadence-column211_d518a6-d9 > .kt-inside-inner-col{flex-direction:column;}.kadence-column211_d518a6-d9 > .kt-inside-inner-col > .aligncenter{width:100%;}.kadence-column211_d518a6-d9 > .kt-inside-inner-col:before{opacity:0.3;}.kadence-column211_d518a6-d9{position:relative;}@media all and (max-width: 1024px){.kadence-column211_d518a6-d9 > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}@media all and (max-width: 767px){.kadence-column211_d518a6-d9 > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}<\/style>\n<div class=\"wp-block-kadence-column kadence-column211_d518a6-d9 inner-column-3\"><div class=\"kt-inside-inner-col\"><style>.wp-block-kadence-column.kb-section-dir-horizontal > .kt-inside-inner-col > .kt-info-box211_192696-a3 .kt-blocks-info-box-link-wrap{max-width:unset;}.kt-info-box211_192696-a3 .kt-blocks-info-box-link-wrap{border-top:5px solid var(--global-palette8, #F7FAFC);border-right:5px solid var(--global-palette8, #F7FAFC);border-bottom:5px solid var(--global-palette8, #F7FAFC);border-left:5px solid var(--global-palette8, #F7FAFC);border-top-left-radius:0px;border-top-right-radius:0px;border-bottom-right-radius:0px;border-bottom-left-radius:0px;background:var(--global-palette8, #F7FAFC);padding-top:20px;padding-right:20px;padding-bottom:20px;padding-left:20px;}.kt-info-box211_192696-a3 .kt-blocks-info-box-link-wrap:hover{background:var(--global-palette7, #EDF2F7);}.kt-info-box211_192696-a3 .kadence-info-box-icon-container .kt-info-svg-icon, .kt-info-box211_192696-a3 .kt-info-svg-icon-flip, .kt-info-box211_192696-a3 .kt-blocks-info-box-number{font-size:30px;}.kt-info-box211_192696-a3 .kt-blocks-info-box-media{color:var(--global-palette9, #ffffff);background:var(--global-palette1, #3182CE);border-color:var(--global-palette8, #F7FAFC);border-top-width:0px;border-right-width:0px;border-bottom-width:0px;border-left-width:0px;padding-top:20px;padding-right:20px;padding-bottom:20px;padding-left:20px;}.kt-info-box211_192696-a3 .kt-blocks-info-box-media-container{margin-top:0px;margin-right:15px;margin-bottom:10px;margin-left:15px;}.kt-info-box211_192696-a3 .kt-blocks-info-box-link-wrap:hover .kt-blocks-info-box-media{color:var(--global-palette9, #ffffff);background:var(--global-palette2, #2B6CB0);}.kt-info-box211_192696-a3 .kt-infobox-textcontent h5.kt-blocks-info-box-title{padding-top:0px;padding-right:0px;padding-bottom:0px;padding-left:0px;margin-top:5px;margin-right:0px;margin-bottom:5px;margin-left:0px;}.kt-info-box211_192696-a3 .kt-infobox-textcontent .kt-blocks-info-box-text{color:#555555;}.kt-info-box211_192696-a3 .kt-blocks-info-box-learnmore{background:transparent;border-color:#555555;border-width:0px 0px 0px 0px;padding-top:4px;padding-right:8px;padding-bottom:4px;padding-left:8px;margin-top:10px;margin-right:0px;margin-bottom:10px;margin-left:0px;}.kt-info-box211_192696-a3 .kt-blocks-info-box-link-wrap:hover .kt-blocks-info-box-learnmore,.kt-info-box211_192696-a3 .kt-blocks-info-box-link-wrap .kt-blocks-info-box-learnmore:focus{color:#ffffff;background:#444444;border-color:#444444;}@media all and (max-width: 1024px){.kt-info-box211_192696-a3 .kt-blocks-info-box-link-wrap{border-top:5px solid var(--global-palette8, #F7FAFC);border-right:5px solid var(--global-palette8, #F7FAFC);border-bottom:5px solid var(--global-palette8, #F7FAFC);border-left:5px solid var(--global-palette8, #F7FAFC);}}@media all and (max-width: 767px){.kt-info-box211_192696-a3 .kt-blocks-info-box-link-wrap{border-top:5px solid var(--global-palette8, #F7FAFC);border-right:5px solid var(--global-palette8, #F7FAFC);border-bottom:5px solid var(--global-palette8, #F7FAFC);border-left:5px solid var(--global-palette8, #F7FAFC);}}<\/style>\n<div class=\"wp-block-kadence-infobox kt-info-box211_192696-a3\"><span class=\"kt-blocks-info-box-link-wrap info-box-link kt-blocks-info-box-media-align-top kt-info-halign-center\"><div class=\"kt-blocks-info-box-media-container\"><div class=\"kt-blocks-info-box-media kt-info-media-animate-none\"><div class=\"kadence-info-box-icon-container kt-info-icon-animate-none\"><div class=\"kadence-info-box-icon-inner-container\"><span class=\"kb-svg-icon-wrap kb-svg-icon-ic_clock kt-info-svg-icon\"><svg viewBox=\"0 0 8 8\"  fill=\"currentColor\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"  aria-hidden=\"true\"><path d=\"M4 0c-2.2 0-4 1.8-4 4s1.8 4 4 4 4-1.8 4-4-1.8-4-4-4zm0 1c1.66 0 3 1.34 3 3s-1.34 3-3 3-3-1.34-3-3 1.34-3 3-3zm-.5 1v2.22l.16.13.5.5.34.38.72-.72-.38-.34-.34-.34v-1.81h-1z\"\/><\/svg><\/span><\/div><\/div><\/div><\/div><div class=\"kt-infobox-textcontent\"><h5 class=\"kt-blocks-info-box-title\"><strong>Total time<\/strong><\/h5><p class=\"kt-blocks-info-box-text\">3 hrs 35 mins<\/p><\/div><\/span><\/div><\/div><\/div>\n<\/div><\/div><h3 class=\"wp-block-heading\">Ingredients:<\/h3><ul class=\"wp-block-list\"><li>1 pound Certified Angus Beef top sirloin cap, cut in 1 1\/2-inch cubes<\/li>\n\n<li>1\/2 c.\u00a0<\/li>\n\n<li>3 dried pasilla peppers<\/li>\n\n<li>2 teaspoons salt<\/li>\n\n<li>1 tablespoon dried oregano<\/li>\n\n<li>1\/2 cup red wine vinegar<\/li>\n\n<li>8-inch skewers as needed<\/li><\/ul><div style=\"height:10px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div><figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"684\" data-src=\"https:\/\/startertemplatecloud.com\/g70\/wp-content\/uploads\/sites\/37\/2022\/07\/pexels-kristya-nugraha-5045087-1024x684.jpg\" alt=\"\" class=\"wp-image-44 lazyload\" data-srcset=\"https:\/\/almoosawirealestate.ae\/meat\/wp-content\/uploads\/2022\/07\/pexels-kristya-nugraha-5045087-1024x684.jpg 1024w, https:\/\/almoosawirealestate.ae\/meat\/wp-content\/uploads\/2022\/07\/pexels-kristya-nugraha-5045087-600x401.jpg 600w, https:\/\/almoosawirealestate.ae\/meat\/wp-content\/uploads\/2022\/07\/pexels-kristya-nugraha-5045087-300x200.jpg 300w, https:\/\/almoosawirealestate.ae\/meat\/wp-content\/uploads\/2022\/07\/pexels-kristya-nugraha-5045087-768x513.jpg 768w, https:\/\/almoosawirealestate.ae\/meat\/wp-content\/uploads\/2022\/07\/pexels-kristya-nugraha-5045087-1536x1026.jpg 1536w, https:\/\/almoosawirealestate.ae\/meat\/wp-content\/uploads\/2022\/07\/pexels-kristya-nugraha-5045087.jpg 1920w\" data-sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" src=\"data:image\/gif;base64,R0lGODlhAQABAAAAACH5BAEKAAEALAAAAAABAAEAAAICTAEAOw==\" style=\"--smush-placeholder-width: 1024px; --smush-placeholder-aspect-ratio: 1024\/684;\" \/><noscript><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"684\" src=\"https:\/\/startertemplatecloud.com\/g70\/wp-content\/uploads\/sites\/37\/2022\/07\/pexels-kristya-nugraha-5045087-1024x684.jpg\" alt=\"\" class=\"wp-image-44\" srcset=\"https:\/\/almoosawirealestate.ae\/meat\/wp-content\/uploads\/2022\/07\/pexels-kristya-nugraha-5045087-1024x684.jpg 1024w, https:\/\/almoosawirealestate.ae\/meat\/wp-content\/uploads\/2022\/07\/pexels-kristya-nugraha-5045087-600x401.jpg 600w, https:\/\/almoosawirealestate.ae\/meat\/wp-content\/uploads\/2022\/07\/pexels-kristya-nugraha-5045087-300x200.jpg 300w, https:\/\/almoosawirealestate.ae\/meat\/wp-content\/uploads\/2022\/07\/pexels-kristya-nugraha-5045087-768x513.jpg 768w, https:\/\/almoosawirealestate.ae\/meat\/wp-content\/uploads\/2022\/07\/pexels-kristya-nugraha-5045087-1536x1026.jpg 1536w, https:\/\/almoosawirealestate.ae\/meat\/wp-content\/uploads\/2022\/07\/pexels-kristya-nugraha-5045087.jpg 1920w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/noscript><\/figure><h3 class=\"wp-block-heading\">Instructions:<\/h3><ol class=\"wp-block-list\"><li>Mix ground meat, breadcrumbs, garlic, chili flakes, salt, and pepper; shape into meatballs.<\/li>\n\n<li>Sear meatballs in a skillet until browned and cooked through.<\/li>\n\n<li>Blend cilantro, parsley, garlic, lemon juice, cumin, paprika, chili flakes, salt, pepper, and olive oil for sauce.<\/li>\n\n<li>Return cooked meatballs to skillet; pour chermoula sauce over meatballs.<\/li>\n\n<li>Simmer meatballs in sauce, then serve hot, garnished with fresh herbs if desired.<\/li><\/ol>","protected":false},"excerpt":{"rendered":"<p>Dive into a burst of flavor with our spicy meatballs accompanied by vibrant chermoula sauce. These succulent meatballs are crafted&#8230;<\/p>\n","protected":false},"author":1,"featured_media":233,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_kad_blocks_custom_css":"","_kad_blocks_head_custom_js":"","_kad_blocks_body_custom_js":"","_kad_blocks_footer_custom_js":"","_kadence_starter_templates_imported_post":true,"_kad_post_transparent":"","_kad_post_title":"","_kad_post_layout":"","_kad_post_sidebar_id":"","_kad_post_content_style":"","_kad_post_vertical_padding":"","_kad_post_feature":"","_kad_post_feature_position":"","_kad_post_header":false,"_kad_post_footer":false,"footnotes":""},"categories":[16],"tags":[],"class_list":["post-211","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-appetizers"],"taxonomy_info":{"category":[{"value":16,"label":"Appetizers"}]},"featured_image_src_large":["https:\/\/almoosawirealestate.ae\/meat\/wp-content\/uploads\/2022\/07\/pexels-snapwire-675951-1024x682.jpg",1024,682,true],"author_info":{"display_name":"admin","author_link":"https:\/\/almoosawirealestate.ae\/meat\/author\/admin\/"},"comment_info":0,"category_info":[{"term_id":16,"name":"Appetizers","slug":"appetizers","term_group":0,"term_taxonomy_id":16,"taxonomy":"category","description":"","parent":0,"count":3,"filter":"raw","cat_ID":16,"category_count":3,"category_description":"","cat_name":"Appetizers","category_nicename":"appetizers","category_parent":0}],"tag_info":false,"_links":{"self":[{"href":"https:\/\/almoosawirealestate.ae\/meat\/wp-json\/wp\/v2\/posts\/211","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/almoosawirealestate.ae\/meat\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/almoosawirealestate.ae\/meat\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/almoosawirealestate.ae\/meat\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/almoosawirealestate.ae\/meat\/wp-json\/wp\/v2\/comments?post=211"}],"version-history":[{"count":1,"href":"https:\/\/almoosawirealestate.ae\/meat\/wp-json\/wp\/v2\/posts\/211\/revisions"}],"predecessor-version":[{"id":1113,"href":"https:\/\/almoosawirealestate.ae\/meat\/wp-json\/wp\/v2\/posts\/211\/revisions\/1113"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/almoosawirealestate.ae\/meat\/wp-json\/wp\/v2\/media\/233"}],"wp:attachment":[{"href":"https:\/\/almoosawirealestate.ae\/meat\/wp-json\/wp\/v2\/media?parent=211"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/almoosawirealestate.ae\/meat\/wp-json\/wp\/v2\/categories?post=211"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/almoosawirealestate.ae\/meat\/wp-json\/wp\/v2\/tags?post=211"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}